{"id":444,"date":"1990-01-01T00:00:13","date_gmt":"1989-12-31T23:00:13","guid":{"rendered":"https:\/\/wp.targetfeld.de\/?p=444"},"modified":"2024-05-03T12:11:02","modified_gmt":"2024-05-03T10:11:02","slug":"dienstleistungen_start","status":"publish","type":"post","link":"https:\/\/targetgroup.de\/en\/dienstleistungen_start\/","title":{"rendered":"dienstleistungen_start"},"content":{"rendered":"<section class=\"about\">\n<div class=\"container\">\n<div class=\"row content\">\n<div class=\"col-lg-5 align-self-center aos-init aos-animate\" data-aos=\"fade-right\" data-aos-delay=\"100\">\n<div class=\"text-center\">\n          <img decoding=\"async\" src=\"\/wp-content\/uploads\/dienstleistungen_01.jpg\" class=\"img-fluid\" alt=\"anytab\">\n        <\/div>\n<\/p><\/div>\n<div class=\"col-lg-7 pt-4 pt-lg-0 aos-init aos-animate\" data-aos=\"fade-left\" data-aos-delay=\"200\">\n<div class=\"section-title aos-init aos-animate\" data-aos=\"fade-right\">\n<h2>Dienstleistungen<\/h2>\n<h4>Individuell auf Sie zugeschnittene L\u00f6sungen<\/h4>\n<\/p><\/div>\n<p>Dienstleistungen sind schwerer zu beschreiben und schwerer zu verkaufen als Produkte, die man anfassen kann<\/p>\n<p><b>Wir helfen Ihnen dabei!<\/b><\/p>\n<p>Ob im B2B Bereich oder im B2C Bereich, wir f\u00fchren f\u00fcr Sie Befragungen durch und helfen Ihnen Ihre Kunden besser zu verstehen!<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Dienstleistungen Individuell auf Sie zugeschnittene L\u00f6sungen Dienstleistungen sind schwerer zu beschreiben und schwerer zu verkaufen als Produkte, die man anfassen kann Wir helfen Ihnen dabei! Ob im B2B Bereich oder im B2C Bereich, wir f\u00fchren f\u00fcr Sie Befragungen durch und helfen Ihnen Ihre Kunden besser zu verstehen!<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-444","post","type-post","status-publish","format-standard","hentry","category-dienstleistungen"],"_links":{"self":[{"href":"https:\/\/targetgroup.de\/en\/wp-json\/wp\/v2\/posts\/444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/targetgroup.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/targetgroup.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/targetgroup.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/targetgroup.de\/en\/wp-json\/wp\/v2\/comments?post=444"}],"version-history":[{"count":1,"href":"https:\/\/targetgroup.de\/en\/wp-json\/wp\/v2\/posts\/444\/revisions"}],"predecessor-version":[{"id":445,"href":"https:\/\/targetgroup.de\/en\/wp-json\/wp\/v2\/posts\/444\/revisions\/445"}],"wp:attachment":[{"href":"https:\/\/targetgroup.de\/en\/wp-json\/wp\/v2\/media?parent=444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/targetgroup.de\/en\/wp-json\/wp\/v2\/categories?post=444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/targetgroup.de\/en\/wp-json\/wp\/v2\/tags?post=444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}